{"id":49698,"date":"2021-03-29T06:04:55","date_gmt":"2021-03-29T06:04:55","guid":{"rendered":"https:\/\/awardforce.com\/?page_id=49698"},"modified":"2026-05-07T11:03:31","modified_gmt":"2026-05-07T11:03:31","slug":"eingabeformular-generator","status":"publish","type":"page","link":"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/eingabeformular-generator\/","title":{"rendered":"Eingabeformular-Generator"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_image=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2021\/04\/Dance.jpg&#8220; height=&#8220;500px&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;150px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_text_color=&#8220;#ffffff&#8220; background_color=&#8220;rgba(0,0,0,0)&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; custom_css_main_element=&#8220;H1   -webkit-text-fill-color: white; \/* Will override color (regardless of order) *\/||    text-shadow: 0px 0px 2px #000, 0px 0px 4px #000;||-webkit-text-stroke-width: 0.1px;||  -webkit-text-stroke-color: #000;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"background-color: #000;\"> Erstellen Sie gro\u00dfartige Eingabeformulare <\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_4,3_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.23.4&#8243; _module_preset=&#8220;default&#8220; header_line_height=&#8220;25px&#8220; header_3_line_height=&#8220;25px&#8220; positioning=&#8220;absolute&#8220; position_origin_a_tablet=&#8220;&#8220; position_origin_a_phone=&#8220;&#8220; position_origin_a_last_edited=&#8220;on|desktop&#8220; position_origin_f_tablet=&#8220;&#8220; position_origin_f_phone=&#8220;&#8220; position_origin_f_last_edited=&#8220;on|desktop&#8220; position_origin_r_tablet=&#8220;&#8220; position_origin_r_phone=&#8220;&#8220; position_origin_r_last_edited=&#8220;on|desktop&#8220; width=&#8220;100%&#8220; custom_margin=&#8220;||0px|||&#8220; custom_padding=&#8220;|||15px|false|false&#8220; sticky_position=&#8220;top&#8220; sticky_limit_bottom=&#8220;body&#8220; positioning_tablet=&#8220;none&#8220; positioning_phone=&#8220;&#8220; positioning_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 class=\"h3\" style=\"padding-left: 15px;\">Award Force Funktionen<\/h3>\n<p><ul class=\"af-features-sidemenu\"><li class=\"page_item page-item-47780 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/\">Gestalten Sie Ihre Auszeichnungen<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49847\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/programmkonfiguration\/\">Programmkonfiguration<\/a><\/li>\n\t<li class=\"page_item page-item-51330\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/datenimport\/\">Datenimport<\/a><\/li>\n\t<li class=\"page_item page-item-49698\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/eingabeformular-generator\/\">Eingabeformular-Generator<\/a><\/li>\n\t<li class=\"page_item page-item-49703\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/unbegrenzte-benutzer-anmeldungen-und-dateien\/\">Unbegrenzte Anzahl von Usern, Eintr\u00e4gen und Dateien<\/a><\/li>\n\t<li class=\"page_item page-item-49650\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/mehrsprachig\/\">Mehrsprachig<\/a><\/li>\n\t<li class=\"page_item page-item-49645\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/online-zahlung\/\">Online-Zahlung<\/a><\/li>\n\t<li class=\"page_item page-item-49631\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/review-flow\/\">Review Flow<\/a><\/li>\n\t<li class=\"page_item page-item-49640\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/streaming-video\/\">Streaming-Video<\/a><\/li>\n\t<li class=\"page_item page-item-49558\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/lieferscheine\/\">Lieferscheine<\/a><\/li>\n\t<li class=\"page_item page-item-49660\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/preisregeln-rabatte\/\">Preisregeln + Rabatte<\/a><\/li>\n\t<li class=\"page_item page-item-49804\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/erste-schritte\/\">Erste Schritte<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47787 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/\">Programmmanagement<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-54732\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/optionale-ki-tools\/\">Optionale KI-Tools<\/a><\/li>\n\t<li class=\"page_item page-item-49829\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/einreichungsmanagement\/\">Einreichungen<\/a><\/li>\n\t<li class=\"page_item page-item-49793\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/rollenverwaltung\/\">Rollenverwaltung<\/a><\/li>\n\t<li class=\"page_item page-item-49783\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/bericht-und-export\/\">Bericht und Export<\/a><\/li>\n\t<li class=\"page_item page-item-49704\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/programmarchivierung\/\">Programmarchivierung<\/a><\/li>\n\t<li class=\"page_item page-item-49655\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/plagiatserkennung\/\">Plagiatserkennung<\/a><\/li>\n\t<li class=\"page_item page-item-49635\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/duplikate-verwalten\/\">Duplikate verwalten<\/a><\/li>\n\t<li class=\"page_item page-item-49573\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/inhaltsverwaltung\/\">Inhaltsverwaltung<\/a><\/li>\n\t<li class=\"page_item page-item-49562\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/moderation\/\">Moderation<\/a><\/li>\n\t<li class=\"page_item page-item-49581\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/kommunizieren\/\">Kommunizieren<\/a><\/li>\n\t<li class=\"page_item page-item-49364\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/sandbox-konto\/\">Sandbox-Konto<\/a><\/li>\n\t<li class=\"page_item page-item-50243\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/multi-chapter\/\">Multi-Chapter<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47783 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/\">Bewertungs-Suite<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49814\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/jury-software\/\">Jury-Software<\/a><\/li>\n\t<li class=\"page_item page-item-49797\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/qualifizierend\/\">Qualifizierend<\/a><\/li>\n\t<li class=\"page_item page-item-49644\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/top-pick\/\">Top Pick<\/a><\/li>\n\t<li class=\"page_item page-item-49674\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/abstimmungssoftware\/\">Abstimmungssoftware<\/a><\/li>\n\t<li class=\"page_item page-item-49669\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/vip-judging\/\">VIP Judging<\/a><\/li>\n\t<li class=\"page_item page-item-49664\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/jury-zuweisungen\/\">Bewertungszuweisungen<\/a><\/li>\n\t<li class=\"page_item page-item-49624\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/ergebnisverwaltung\/\">Ergebnisverwaltung<\/a><\/li>\n\t<li class=\"page_item page-item-49627\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/jury-feedback\/\">Jury-Feedback<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47728 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/\">Funktionen zur Unterst\u00fctzung der Teilnehmenden<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49842\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/zusammenarbeit-bei-der-einreichung-fur-auszeichnungen\/\">Zusammenarbeit bei der Einreichung f\u00fcr Auszeichnungen<\/a><\/li>\n\t<li class=\"page_item page-item-49789\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/registrierungsoptionen\/\">Registrierungsoptionen<\/a><\/li>\n\t<li class=\"page_item page-item-49694\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/dateitypen-und-anhange\/\">Dateitypen und Anh\u00e4nge<\/a><\/li>\n\t<li class=\"page_item page-item-49687\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/barrierefreiheit\/\">Barrierefreiheit<\/a><\/li>\n\t<li class=\"page_item page-item-49579\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/fehlervermeidung\/\">Fehlervermeidung<\/a><\/li>\n\t<li class=\"page_item page-item-50963\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/online-einreichung-von-auszeichnungen\/\">Online-Auszeichnungseingabe<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47724 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/\">F\u00f6rdern<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49786\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/sponsor-sichtbarkeit\/\">Sponsor-Sichtbarkeit<\/a><\/li>\n\t<li class=\"page_item page-item-49679\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/galerien\/\">Galerien<\/a><\/li>\n\t<li class=\"page_item page-item-49683\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/soziales-teilen\/\">Soziales Teilen<\/a><\/li>\n\t<li class=\"page_item page-item-49801\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/branding\/\">Branding<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47720 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/\">Sch\u00fctzen<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49410\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/audit-protokoll\/\">Audit-Protokoll<\/a><\/li>\n\t<li class=\"page_item page-item-49668\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/datenresidenz\/\">Datenresidenz<\/a><\/li>\n\t<li class=\"page_item page-item-49397\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/pii\/\">PII<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47777 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/\">Integrieren<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49488\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/google-tabellen\/\">Google Tabellen<\/a><\/li>\n\t<li class=\"page_item page-item-49465\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/hubspot\/\">Hubspot<\/a><\/li>\n\t<li class=\"page_item page-item-49447\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/mailchimp\/\">Mailchimp<\/a><\/li>\n\t<li class=\"page_item page-item-49495\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/microsoft-dynamics\/\">Microsoft Dynamics<\/a><\/li>\n\t<li class=\"page_item page-item-49475\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/salesforce\/\">Salesforce<\/a><\/li>\n\t<li class=\"page_item page-item-49425\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/make\/\">Make<\/a><\/li>\n\t<li class=\"page_item page-item-49389\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/integrations-marktplatz\/\">Integrations-Marktplatz<\/a><\/li>\n\t<li class=\"page_item page-item-49440\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/google-formulare\/\">Google Formulare<\/a><\/li>\n\t<li class=\"page_item page-item-49451\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/zoom\/\">Zoom<\/a><\/li>\n\t<li class=\"page_item page-item-49455\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/zapier\/\">Zapier<\/a><\/li>\n\t<li class=\"page_item page-item-49480\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/wordpress\/\">WordPress<\/a><\/li>\n\t<li class=\"page_item page-item-49484\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/xero\/\">Xero<\/a><\/li>\n\t<li class=\"page_item page-item-49535\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/docusign\/\">DocuSign<\/a><\/li>\n\t<li class=\"page_item page-item-49541\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/eventbrite\/\">Eventbrite<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.23.4&#8243; header_2_line_height=&#8220;1.4em&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 id=\"main\" style=\"text-align: left;\">Bieten Sie au\u00dfergew\u00f6hnliche Erlebnisse f\u00fcr Teilnehmende mit dem weltweit leistungsst\u00e4rksten Formular-Builder f\u00fcr Einreichungen.<\/h2>\n<h3 class=\"h4\" style=\"text-align: left;\">Erstellen Sie m\u00fchelos anspruchsvolle Formulare, die Ihre Teilnehmende lieben werden. Organisieren Sie Ihr Formular mit Kapiteln, Kategorien und Tabs. Nutzen Sie bedingte Logik, um zus\u00e4tzliche Informationen abzufragen. Bieten Sie Ihren Teilnehmenden kontextbezogene Hilfe. Und tun Sie dies alles in einer oder mehreren Sprachen, w\u00e4hrend Sie globale Datenschutzstandards wie GDPR und CCPA einhalten.    <\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_margin=&#8220;|auto|1px|auto|false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.23.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Jeder kann es nutzen<\/h3>\n<p>Erstellen Sie ansprechende, einzigartige und benutzerfreundliche Formulare mit einer Reihe hoch entwickelter Optionen, die so einfach zu bedienen sind, dass Sie sich fragen werden, warum andere Software nicht so aufgebaut ist.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>F\u00fcr alle User zug\u00e4nglich<\/h3>\n<p><span>Award Force <a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/barrierefreiheit\/\">entspricht den WCAG 2.2 AA Standards<\/a><\/span><span>, was bedeutet, dass Award Force von Menschen mit Behinderung als wahrnehmbar, bedienbar, verst\u00e4ndlich und robust angesehen wird.<\/span>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Datenschutzfunktionen, Standard<\/h3>\n<p>Erf\u00fcllen Sie sowohl die GDPR als auch die CCPA. Einzelne Antworten auf spezifische Fragen k\u00f6nnen unter mehreren zunehmend sicheren Optionen gesch\u00fctzt werden. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_padding=&#8220;1px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Mehrsprachig<\/h3>\n<p>Erstellen Sie Ihr Einreichungsformular gleichzeitig in einer oder mehreren Sprachen. Sie k\u00f6nnen neben mehr als 30 professionell \u00fcbersetzten Systemsprachen lokalisieren. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Vielf\u00e4ltige Fragetypen<\/h3>\n<p><span>W\u00e4hlen Sie aus mehr als 18 verschiedenen Fragetypen, einschlie\u00dflich spezialisierter Felder wie Formel, numerisch, Datum, E-Mail, Tabelle, URL, Land und viele mehr.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Mobilfreundliche Formulare<\/h3>\n<p>Erstellen Sie vollst\u00e4ndig responsive Formulare, die sich automatisch an die Ger\u00e4te Ihrer Teilnehmenden anpassen und ein konsistentes Erlebnis f\u00fcr alle Teilnehmenden schaffen. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,3_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Mehr erreichen in weniger Zeit<\/h2>\n<p><span>Erstellen, bearbeiten und zeigen Sie Ihr Eingabeformular schnell an einem Ort online an. Keine Programmierung oder spezielle Kenntnisse erforderlich. <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>1. Wechseln Sie in Sekundenschnelle zwischen Bearbeitung und Vorschau<\/p>\n<p>2. Greifen Sie auf leistungsstarke Frageeinstellungen f\u00fcr die Bearbeitung im Handumdrehen zu<\/p>\n<p>3. Formular-Tabs sofort hinzuf\u00fcgen, entfernen und bearbeiten<\/p>\n<p>4. Kontextbezogene Informationen wie Hilfe, Tipps, Links und sogar Videos \u00fcberall dort platzieren, wo Sie ein Bleistiftsymbol sehen<\/p>\n<p>5. Neue Fragen dynamisch hinzuf\u00fcgen<\/p>\n<p>6. Fragen per Drag  Drop ziehen und Frageeinstellungen aufrufen<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2022\/10\/Awards-Management-software-entryform-builder.png&#8220; alt=&#8220;Eingabeformulare f\u00fcr Award-Management-Software&#8220; title_text=&#8220;Awards-Management-Software-Eingabeformular-Builder&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_2,1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2022\/10\/Awards-management-entry-form.gif&#8220; alt=&#8220;Eingabeformular f\u00fcr die Auszeichnungsverwaltung&#8220; title_text=&#8220;Eingabeformular f\u00fcr die Auszeichnungsverwaltung&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Einfache Drag-and-Drop-Bearbeitung<\/h3>\n<p>Passen Sie Ihr Eingabeformular visuell in Echtzeit an.<\/p>\n<p>Ziehen Sie die Fragenreihenfolge auf demselben Tab per Drag  Drop, verschieben Sie Fragen auf andere Tabs und ordnen Sie die Tabs selbst neu an, um ein Formular zu erstellen, das Ihre Teilnehmende lieben werden.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Optionale KI-Felder<\/h3>\n<p><span>Sparen Sie Zeit und arbeiten Sie schnell mit Einreichungsdaten \u2013 mit den KI-Feldern von Award Force. Direkt in Ihrem Einreichungsformular konfiguriert, kann dieser Feldtyp automatisch \u2013 oder auf Wunsch einzeln \u2013 klare, pr\u00e4zise Zusammenfassungen und Erkenntnisse \u00fcber alle Einreichungen liefern, ob beim Pr\u00fcfen von Einreichungen, beim Vorbereiten der Ergebnisse oder beim Formulieren von Gewinner-Lobtexten. Und das alles, w\u00e4hrend Ihre Daten sicher bleiben und Ihr Bewertungsprozess fair ist. <\/span>[\/et_pb_text][dsm_button button_one_text=&#8220;Mehr \u00fcber die KI-Felder&#8220; button_one_url=&#8220;https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/optionale-ki-tools\/&#8220; button_one_url_new_window=&#8220;on&#8220; button_one_text_tablet=&#8220;Weitere Eingabeaufforderungen anzeigen&#8220; button_one_text_phone=&#8220;Weitere Eingabeaufforderungen anzeigen&#8220; button_one_text_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_button_one=&#8220;on&#8220; button_one_text_color=&#8220;#3B47F4&#8243; button_one_bg_color=&#8220;RGBA(255,255,255,0)&#8220; button_one_border_width=&#8220;0px&#8220; button_one_border_radius=&#8220;0px&#8220; button_one_font=&#8220;&#8211;et_global_heading_font|600|||||||&#8220; button_one_icon=&#8220;&#xf105;||fa||900&#8243; button_one_on_hover=&#8220;off&#8220; button_one_custom_padding=&#8220;|||0px|false|false&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;10px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/dsm_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2026\/05\/AF-UI-Entry-AI-Overlay-DE.png&#8220; alt=&#8220;Award Force optionale KI-Felder&#8220; title_text=&#8220;AF-UI-Entry-AI-Overlay-DE&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_2,1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2022\/10\/AF_Overview_Build_Autoscore.png&#8220; alt=&#8220;Bewertung in Award-Management-Software&#8220; title_text=&#8220;Bewertung in Award-Management-Software&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Automatische Bewertung f\u00fcr einfache Einreichungsmoderation<\/h3>\n<p><span>Moderieren Sie Einreichungen automatisch, indem Sie Antworten auf spezifische Fragen basierend auf Ihren vordefinierten Kriterien Punkte zuweisen.<\/span><\/p>\n<p><span>Sortieren Sie von der h\u00f6chsten zur niedrigsten Punktzahl, sehen Sie eine Aufschl\u00fcsselung der Antworten jeder Einreichung mit einer automatischen Bewertungsmatrix und \u00fcberpr\u00fcfen Sie schnell Ihre Award-Einreichungen.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Mehr abgeschlossene Einreichungen erhalten<\/h3>\n<p><span>Unterst\u00fctzen Sie Teilnehmende mit Hilfestellungen, Tipps und Anleitungen in jeder Phase ihrer Einreichung.<\/span><\/p>\n<p><span>Sie k\u00f6nnen einzelnen Fragen Hinweis- und Hilfetexte hinzuf\u00fcgen und durch eine Reihe von Informationsbereichen auf dem Einreichungsformular, die <\/span>Text, Bilder und sogar Videos umfassen, einen Dialog mit Usern aufbauen, um ein reichhaltiges, markenf\u00f6rderndes Erlebnis zu schaffen.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2022\/10\/Awards-mamangement-Entrant1.png&#8220; alt=&#8220;Hinweise zur Award-Management-Software&#8220; title_text=&#8220;Awards-Management-Teilnehmende1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; module_alignment=&#8220;right&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_2,1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2022\/10\/Awards-mamangement-entry-forms-conditional.png&#8220; alt=&#8220;Award-Management-Software bedingte Logik&#8220; title_text=&#8220;Awards-Management-Einreichungsformulare-bedingt&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Bedingte Logik f\u00fcr personalisierte Erlebnisse<\/h3>\n<p><span>Schaffen Sie ein dynamisches, intelligentes und pers\u00f6nliches Erlebnis f\u00fcr Teilnehmende. Zeigen oder verbergen Sie spezifische Fragen basierend auf den Antworten fr\u00fcherer Fragen. <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;85%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Einzigartige Fragen f\u00fcr spezifische Kategorien<\/h3>\n<p><span>Betreiben Sie Ihr Award-Programm mit mehreren Kategorien? Kein Problem. Sie k\u00f6nnen Ihr Einreichungsformular so konfigurieren, dass es spezifische Fragen in spezifischen Kategorien stellt und sicherstellt, dass Ihre Teilnehmende nur relevante und aussagekr\u00e4ftige Fragen in Ihrem Formular sehen.  <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/awardforce.com\/wp-content\/uploads\/2022\/10\/Awards-mamangement-entry-forms-categories.png&#8220; alt=&#8220;Kategorien des Eingabeformulars f\u00fcr die Auszeichnungsverwaltung&#8220; title_text=&#8220;Awards-Management-Einreichungsformulare-Kategorien&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#e9edf4&#8243; custom_margin=&#8220;50px||||false|false&#8220; custom_padding=&#8220;0px||3px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;|20px|1px|20px|false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 id=\"faqs\">H\u00e4ufig gestellte Fragen<!-- [et_pb_line_break_holder] --><\/h2>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;10px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dsm_faq dsm_accordion_gap=&#8220;1px&#8220; dsm_open_bg_color=&#8220;RGBA(255,255,255,0)&#8220; dsm_open_toggle_padding=&#8220;|||0px|false|false&#8220; dsm_close_bg_color=&#8220;RGBA(255,255,255,0)&#8220; dsm_closed_toggle_margin=&#8220;||||false|false&#8220; dsm_closed_toggle_padding=&#8220;|||0px|false|false&#8220; dsm_open_font_icon=&#8220;&#x3a;||divi||400&#8243; dsm_close_font_icon=&#8220;&#x3b;||divi||400&#8243; dsm_open_icon_bg_color=&#8220;RGBA(255,255,255,0)&#8220; dsm_close_icon_bg_color=&#8220;RGBA(255,255,255,0)&#8220; dsm_close_icon_color=&#8220;#242424&#8243; dsm_icon_placement=&#8220;right&#8220; dsm_content_padding=&#8220;15px||||false|false&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;&#8211;et_global_heading_font|500|||||||&#8220; header_font_size=&#8220;18px&#8220; header_line_height=&#8220;1.5em&#8220; closed_header_font=&#8220;&#8211;et_global_heading_font|500|||||||&#8220; closed_header_text_color=&#8220;#242424&#8243; closed_header_font_size=&#8220;18px&#8220; closed_header_line_height=&#8220;1.5em&#8220; content_line_height=&#8220;1.8em&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; overflow-x=&#8220;visible&#8220; overflow-y=&#8220;visible&#8220; hover_transition_duration=&#8220;150ms&#8220; border_color_all_dsm_toggle_open_border=&#8220;#242424&#8243; border_width_bottom_dsm_toggle_open_border=&#8220;1.5px&#8220; border_color_bottom_dsm_toggle_open_border=&#8220;rgba(10,0,0,0.18)&#8220; border_radii_dsm_toggle_closed_border=&#8220;off||||&#8220; border_color_all_dsm_toggle_closed_border=&#8220;#242424&#8243; border_width_bottom_dsm_toggle_closed_border=&#8220;1.5px&#8220; border_color_bottom_dsm_toggle_closed_border=&#8220;rgba(10,0,0,0.18)&#8220; global_colors_info=&#8220;{}&#8220;][dsm_faq_child dsm_title=&#8220;Kann ich Formulare ohne Programmierung erstellen?&#8220; dsm_content=&#8220;Ja. Award Force verwendet einen visuellen Drag-and-Drop-Formular-Builder, mit dem Sie Fragen, Dateiuploads, Anleitungstexte und bedingte Logik hinzuf\u00fcgen k\u00f6nnen, ohne Code schreiben zu m\u00fcssen. &#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; border_style_top_dsm_toggle_open_border=&#8220;none&#8220; border_style_right_dsm_toggle_open_border=&#8220;none&#8220; border_style_left_dsm_toggle_open_border=&#8220;none&#8220; border_style_top_dsm_toggle_closed_border=&#8220;none&#8220; border_style_right_dsm_toggle_closed_border=&#8220;none&#8220; border_style_left_dsm_toggle_closed_border=&#8220;none&#8220; global_colors_info=&#8220;{}&#8220; parentOrderClass=&#8220;dsm_faq_0&#8243;][\/dsm_faq_child][dsm_faq_child dsm_title=&#8220;Kann ich verschiedene Fragen basierend auf vorherigen Antworten anzeigen?&#8220; dsm_content=&#8220;Ja. Sie k\u00f6nnen Fragen basierend auf vorherigen Antworten anzeigen oder verbergen, sodass Teilnehmende nur Fragen sehen, die f\u00fcr sie relevant sind. &#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; border_style_top_dsm_toggle_open_border=&#8220;none&#8220; border_style_right_dsm_toggle_open_border=&#8220;none&#8220; border_style_left_dsm_toggle_open_border=&#8220;none&#8220; border_style_top_dsm_toggle_closed_border=&#8220;none&#8220; border_style_right_dsm_toggle_closed_border=&#8220;none&#8220; border_style_left_dsm_toggle_closed_border=&#8220;none&#8220; global_colors_info=&#8220;{}&#8220; parentOrderClass=&#8220;dsm_faq_0&#8243;][\/dsm_faq_child][dsm_faq_child dsm_title=&#8220;Kann ich Hilfetexte oder Anleitungen im Formular hinzuf\u00fcgen?&#8220; dsm_content=&#8220;Ja. Sie k\u00f6nnen Anweisungen, Tipps, Links oder kontextbezogene Anleitungen direkt in das Formular einf\u00fcgen. &#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; border_style_top_dsm_toggle_open_border=&#8220;none&#8220; border_style_right_dsm_toggle_open_border=&#8220;none&#8220; border_style_left_dsm_toggle_open_border=&#8220;none&#8220; border_style_top_dsm_toggle_closed_border=&#8220;none&#8220; border_style_right_dsm_toggle_closed_border=&#8220;none&#8220; border_style_left_dsm_toggle_closed_border=&#8220;none&#8220; global_colors_info=&#8220;{}&#8220; parentOrderClass=&#8220;dsm_faq_0&#8243;][\/dsm_faq_child][dsm_faq_child dsm_title=&#8220;Kann ich das Formular in mehreren Sprachen erstellen?&#8220; dsm_content=&#8220;Ja. Einreichungsformulare k\u00f6nnen in mehreren Sprachen erstellt und zur Verf\u00fcgung gestellt werden, sodass Teilnehmende das Formular in ihrer bevorzugten Sprache ausf\u00fcllen k\u00f6nnen. &#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; border_style_top_dsm_toggle_open_border=&#8220;none&#8220; border_style_right_dsm_toggle_open_border=&#8220;none&#8220; border_style_left_dsm_toggle_open_border=&#8220;none&#8220; border_style_top_dsm_toggle_closed_border=&#8220;none&#8220; border_style_right_dsm_toggle_closed_border=&#8220;none&#8220; border_style_left_dsm_toggle_closed_border=&#8220;none&#8220; global_colors_info=&#8220;{}&#8220; parentOrderClass=&#8220;dsm_faq_0&#8243;][\/dsm_faq_child][\/dsm_faq][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erstellen Sie gro\u00dfartige Eingabeformulare Award Force Funktionen <ul class=\"af-features-sidemenu\"><li class=\"page_item page-item-47780 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/\">Gestalten Sie Ihre Auszeichnungen<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49847\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/programmkonfiguration\/\">Programmkonfiguration<\/a><\/li>\n\t<li class=\"page_item page-item-51330\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/datenimport\/\">Datenimport<\/a><\/li>\n\t<li class=\"page_item page-item-49698\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/eingabeformular-generator\/\">Eingabeformular-Generator<\/a><\/li>\n\t<li class=\"page_item page-item-49703\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/unbegrenzte-benutzer-anmeldungen-und-dateien\/\">Unbegrenzte Anzahl von Usern, Eintr\u00e4gen und Dateien<\/a><\/li>\n\t<li class=\"page_item page-item-49650\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/mehrsprachig\/\">Mehrsprachig<\/a><\/li>\n\t<li class=\"page_item page-item-49645\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/online-zahlung\/\">Online-Zahlung<\/a><\/li>\n\t<li class=\"page_item page-item-49631\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/review-flow\/\">Review Flow<\/a><\/li>\n\t<li class=\"page_item page-item-49640\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/streaming-video\/\">Streaming-Video<\/a><\/li>\n\t<li class=\"page_item page-item-49558\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/lieferscheine\/\">Lieferscheine<\/a><\/li>\n\t<li class=\"page_item page-item-49660\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/preisregeln-rabatte\/\">Preisregeln + Rabatte<\/a><\/li>\n\t<li class=\"page_item page-item-49804\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/erstellen-sie-ihre-auszeichnungen\/erste-schritte\/\">Erste Schritte<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47787 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/\">Programmmanagement<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-54732\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/optionale-ki-tools\/\">Optionale KI-Tools<\/a><\/li>\n\t<li class=\"page_item page-item-49829\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/einreichungsmanagement\/\">Einreichungen<\/a><\/li>\n\t<li class=\"page_item page-item-49793\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/rollenverwaltung\/\">Rollenverwaltung<\/a><\/li>\n\t<li class=\"page_item page-item-49783\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/bericht-und-export\/\">Bericht und Export<\/a><\/li>\n\t<li class=\"page_item page-item-49704\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/programmarchivierung\/\">Programmarchivierung<\/a><\/li>\n\t<li class=\"page_item page-item-49655\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/plagiatserkennung\/\">Plagiatserkennung<\/a><\/li>\n\t<li class=\"page_item page-item-49635\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/duplikate-verwalten\/\">Duplikate verwalten<\/a><\/li>\n\t<li class=\"page_item page-item-49573\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/inhaltsverwaltung\/\">Inhaltsverwaltung<\/a><\/li>\n\t<li class=\"page_item page-item-49562\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/moderation\/\">Moderation<\/a><\/li>\n\t<li class=\"page_item page-item-49581\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/kommunizieren\/\">Kommunizieren<\/a><\/li>\n\t<li class=\"page_item page-item-49364\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/sandbox-konto\/\">Sandbox-Konto<\/a><\/li>\n\t<li class=\"page_item page-item-50243\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/programmmanagement\/multi-chapter\/\">Multi-Chapter<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47783 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/\">Bewertungs-Suite<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49814\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/jury-software\/\">Jury-Software<\/a><\/li>\n\t<li class=\"page_item page-item-49797\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/qualifizierend\/\">Qualifizierend<\/a><\/li>\n\t<li class=\"page_item page-item-49644\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/top-pick\/\">Top Pick<\/a><\/li>\n\t<li class=\"page_item page-item-49674\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/abstimmungssoftware\/\">Abstimmungssoftware<\/a><\/li>\n\t<li class=\"page_item page-item-49669\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/vip-judging\/\">VIP Judging<\/a><\/li>\n\t<li class=\"page_item page-item-49664\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/jury-zuweisungen\/\">Bewertungszuweisungen<\/a><\/li>\n\t<li class=\"page_item page-item-49624\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/ergebnisverwaltung\/\">Ergebnisverwaltung<\/a><\/li>\n\t<li class=\"page_item page-item-49627\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/jury-suite\/jury-feedback\/\">Jury-Feedback<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47728 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/\">Funktionen zur Unterst\u00fctzung der Teilnehmenden<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49842\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/zusammenarbeit-bei-der-einreichung-fur-auszeichnungen\/\">Zusammenarbeit bei der Einreichung f\u00fcr Auszeichnungen<\/a><\/li>\n\t<li class=\"page_item page-item-49789\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/registrierungsoptionen\/\">Registrierungsoptionen<\/a><\/li>\n\t<li class=\"page_item page-item-49694\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/dateitypen-und-anhange\/\">Dateitypen und Anh\u00e4nge<\/a><\/li>\n\t<li class=\"page_item page-item-49687\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/barrierefreiheit\/\">Barrierefreiheit<\/a><\/li>\n\t<li class=\"page_item page-item-49579\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/fehlervermeidung\/\">Fehlervermeidung<\/a><\/li>\n\t<li class=\"page_item page-item-50963\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/funktionen-zur-unterstutzung-der-teilnehmer\/online-einreichung-von-auszeichnungen\/\">Online-Auszeichnungseingabe<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47724 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/\">F\u00f6rdern<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49786\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/sponsor-sichtbarkeit\/\">Sponsor-Sichtbarkeit<\/a><\/li>\n\t<li class=\"page_item page-item-49679\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/galerien\/\">Galerien<\/a><\/li>\n\t<li class=\"page_item page-item-49683\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/soziales-teilen\/\">Soziales Teilen<\/a><\/li>\n\t<li class=\"page_item page-item-49801\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/markenwerbung\/branding\/\">Branding<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47720 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/\">Sch\u00fctzen<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49410\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/audit-protokoll\/\">Audit-Protokoll<\/a><\/li>\n\t<li class=\"page_item page-item-49668\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/datenresidenz\/\">Datenresidenz<\/a><\/li>\n\t<li class=\"page_item page-item-49397\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/sichern-sie-ihre-awards\/pii\/\">PII<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"page_item page-item-47777 page_item_has_children\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/\">Integrieren<\/a>\n<ul class='children'>\n\t<li class=\"page_item page-item-49488\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/google-tabellen\/\">Google Tabellen<\/a><\/li>\n\t<li class=\"page_item page-item-49465\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/hubspot\/\">Hubspot<\/a><\/li>\n\t<li class=\"page_item page-item-49447\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/mailchimp\/\">Mailchimp<\/a><\/li>\n\t<li class=\"page_item page-item-49495\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/microsoft-dynamics\/\">Microsoft Dynamics<\/a><\/li>\n\t<li class=\"page_item page-item-49475\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/salesforce\/\">Salesforce<\/a><\/li>\n\t<li class=\"page_item page-item-49425\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/make\/\">Make<\/a><\/li>\n\t<li class=\"page_item page-item-49389\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/integrations-marktplatz\/\">Integrations-Marktplatz<\/a><\/li>\n\t<li class=\"page_item page-item-49440\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/google-formulare\/\">Google Formulare<\/a><\/li>\n\t<li class=\"page_item page-item-49451\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/zoom\/\">Zoom<\/a><\/li>\n\t<li class=\"page_item page-item-49455\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/zapier\/\">Zapier<\/a><\/li>\n\t<li class=\"page_item page-item-49480\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/wordpress\/\">WordPress<\/a><\/li>\n\t<li class=\"page_item page-item-49484\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/xero\/\">Xero<\/a><\/li>\n\t<li class=\"page_item page-item-49535\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/docusign\/\">DocuSign<\/a><\/li>\n\t<li class=\"page_item page-item-49541\"><a href=\"https:\/\/awardforce.com\/de\/funktionen\/integrieren\/eventbrite\/\">Eventbrite<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>Bieten Sie au\u00dfergew\u00f6hnliche Erlebnisse f\u00fcr Teilnehmende mit dem weltweit leistungsst\u00e4rksten Formular-Builder f\u00fcr Einreichungen. Erstellen Sie m\u00fchelos anspruchsvolle Formulare, die Ihre Teilnehmende lieben werden. Organisieren Sie Ihr Formular mit Kapiteln, Kategorien und Tabs. Nutzen Sie bedingte Logik, um zus\u00e4tzliche Informationen abzufragen. Bieten Sie Ihren Teilnehmenden kontextbezogene Hilfe. Und tun Sie dies alles in einer oder mehreren Sprachen, w\u00e4hrend Sie globale Datenschutzstandards wie GDPR und CCPA einhalten. Jeder kann es nutzen Erstellen Sie ansprechende, einzigartige und benutzerfreundliche Formulare mit einer Reihe hoch entwickelter Optionen, die so einfach zu bedienen sind, dass Sie sich fragen werden, warum andere Software nicht so aufgebaut ist.F\u00fcr alle User zug\u00e4nglich Award Force entspricht den WCAG 2.2 AA Standards, was bedeutet, dass Award Force von Menschen mit Behinderung als wahrnehmbar, bedienbar, verst\u00e4ndlich und robust angesehen wird.Datenschutzfunktionen, Standard Erf\u00fcllen Sie sowohl die GDPR als auch die CCPA. Einzelne Antworten auf spezifische Fragen k\u00f6nnen unter mehreren zunehmend sicheren Optionen gesch\u00fctzt werden. Mehrsprachig Erstellen Sie Ihr Einreichungsformular gleichzeitig in einer oder mehreren Sprachen. Sie k\u00f6nnen neben mehr als 30 professionell \u00fcbersetzten Systemsprachen lokalisieren. Vielf\u00e4ltige Fragetypen W\u00e4hlen Sie aus mehr als 18 verschiedenen Fragetypen, einschlie\u00dflich spezialisierter Felder wie Formel, numerisch, Datum, E-Mail, Tabelle, URL, Land [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49699,"parent":47780,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-49698","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/pages\/49698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/comments?post=49698"}],"version-history":[{"count":5,"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/pages\/49698\/revisions"}],"predecessor-version":[{"id":60129,"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/pages\/49698\/revisions\/60129"}],"up":[{"embeddable":true,"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/pages\/47780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/media\/49699"}],"wp:attachment":[{"href":"https:\/\/awardforce.com\/de\/wp-json\/wp\/v2\/media?parent=49698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}